{"id":3905,"date":"2017-06-04T18:48:51","date_gmt":"2017-06-04T18:48:51","guid":{"rendered":"http:\/\/houstonmusicreview.com\/wordpress\/wp-content\/uploads\/2017\/06\/U2-13.jpg"},"modified":"2017-06-04T18:48:51","modified_gmt":"2017-06-04T18:48:51","slug":"u2-13","status":"inherit","type":"attachment","link":"http:\/\/houstonmusicreview.com\/wordpress\/2017\/06\/04\/u2-nrg-stadium-houston-tx-052417-photos\/u2-13\/","title":{"rendered":"U2-13"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-3905","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='http:\/\/houstonmusicreview.com\/wordpress\/wp-content\/uploads\/2017\/06\/U2-13.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"240\" src=\"http:\/\/houstonmusicreview.com\/wordpress\/wp-content\/uploads\/2017\/06\/U2-13-300x240.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"http:\/\/houstonmusicreview.com\/wordpress\/wp-content\/uploads\/2017\/06\/U2-13-300x240.jpg 300w, http:\/\/houstonmusicreview.com\/wordpress\/wp-content\/uploads\/2017\/06\/U2-13.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-attachment-id=\"3905\" data-permalink=\"http:\/\/houstonmusicreview.com\/wordpress\/2017\/06\/04\/u2-nrg-stadium-houston-tx-052417-photos\/u2-13\/\" data-orig-file=\"http:\/\/houstonmusicreview.com\/wordpress\/wp-content\/uploads\/2017\/06\/U2-13.jpg\" data-orig-size=\"600,480\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS-1D X&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1495656910&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;560&quot;,&quot;iso&quot;:&quot;2000&quot;,&quot;shutter_speed&quot;:&quot;0.0015625&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"U2-13\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"http:\/\/houstonmusicreview.com\/wordpress\/wp-content\/uploads\/2017\/06\/U2-13.jpg\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":600,"height":480,"file":"2017\/06\/U2-13.jpg","sizes":{"thumbnail":{"file":"U2-13-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"http:\/\/houstonmusicreview.com\/wordpress\/wp-content\/uploads\/2017\/06\/U2-13-150x150.jpg"},"medium":{"file":"U2-13-300x240.jpg","width":300,"height":240,"mime_type":"image\/jpeg","source_url":"http:\/\/houstonmusicreview.com\/wordpress\/wp-content\/uploads\/2017\/06\/U2-13-300x240.jpg"},"post-thumbnail":{"file":"U2-13-600x300.jpg","width":600,"height":300,"mime_type":"image\/jpeg","source_url":"http:\/\/houstonmusicreview.com\/wordpress\/wp-content\/uploads\/2017\/06\/U2-13-600x300.jpg"},"full":{"file":"U2-13.jpg","width":600,"height":480,"mime_type":"image\/jpeg","source_url":"http:\/\/houstonmusicreview.com\/wordpress\/wp-content\/uploads\/2017\/06\/U2-13.jpg"}},"image_meta":{"aperture":"4","credit":"","camera":"Canon EOS-1D X","caption":"","created_timestamp":"1495656910","copyright":"","focal_length":"560","iso":"2000","shutter_speed":"0.0015625","title":"","orientation":"0","keywords":[]}},"post":3896,"source_url":"http:\/\/houstonmusicreview.com\/wordpress\/wp-content\/uploads\/2017\/06\/U2-13.jpg","_links":{"self":[{"href":"http:\/\/houstonmusicreview.com\/wordpress\/wp-json\/wp\/v2\/media\/3905","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/houstonmusicreview.com\/wordpress\/wp-json\/wp\/v2\/media"}],"about":[{"href":"http:\/\/houstonmusicreview.com\/wordpress\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"http:\/\/houstonmusicreview.com\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/houstonmusicreview.com\/wordpress\/wp-json\/wp\/v2\/comments?post=3905"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":3896,"href":"http:\/\/houstonmusicreview.com\/wordpress\/wp-json\/wp\/v2\/posts\/3896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}