{"id":7200,"date":"2019-11-14T02:28:58","date_gmt":"2019-11-14T02:28:58","guid":{"rendered":"http:\/\/houstonmusicreview.com\/wordpress\/wp-content\/uploads\/2019\/11\/Kevin-Black-Photography-2708.jpg"},"modified":"2019-11-14T02:28:58","modified_gmt":"2019-11-14T02:28:58","slug":"kevin-black-photography-2708","status":"inherit","type":"attachment","link":"https:\/\/houstonmusicreview.com\/wordpress\/2019\/11\/14\/vetsaid-toyota-center-houston-tx-photos\/kevin-black-photography-2708\/","title":{"rendered":"Kevin Black Photography-2708"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-7200","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/houstonmusicreview.com\/wordpress\/wp-content\/uploads\/2019\/11\/Kevin-Black-Photography-2708.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/houstonmusicreview.com\/wordpress\/wp-content\/uploads\/2019\/11\/Kevin-Black-Photography-2708-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/houstonmusicreview.com\/wordpress\/wp-content\/uploads\/2019\/11\/Kevin-Black-Photography-2708-300x200.jpg 300w, https:\/\/houstonmusicreview.com\/wordpress\/wp-content\/uploads\/2019\/11\/Kevin-Black-Photography-2708-768x512.jpg 768w, https:\/\/houstonmusicreview.com\/wordpress\/wp-content\/uploads\/2019\/11\/Kevin-Black-Photography-2708.jpg 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-attachment-id=\"7200\" data-permalink=\"https:\/\/houstonmusicreview.com\/wordpress\/2019\/11\/14\/vetsaid-toyota-center-houston-tx-photos\/kevin-black-photography-2708\/\" data-orig-file=\"https:\/\/houstonmusicreview.com\/wordpress\/wp-content\/uploads\/2019\/11\/Kevin-Black-Photography-2708.jpg\" data-orig-size=\"1000,667\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS-1D Mark IV&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1573418883&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;400&quot;,&quot;iso&quot;:&quot;2500&quot;,&quot;shutter_speed&quot;:&quot;0.0025&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Kevin Black Photography-2708\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/houstonmusicreview.com\/wordpress\/wp-content\/uploads\/2019\/11\/Kevin-Black-Photography-2708.jpg\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1000,"height":667,"file":"2019\/11\/Kevin-Black-Photography-2708.jpg","sizes":{"thumbnail":{"file":"Kevin-Black-Photography-2708-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/houstonmusicreview.com\/wordpress\/wp-content\/uploads\/2019\/11\/Kevin-Black-Photography-2708-150x150.jpg"},"medium":{"file":"Kevin-Black-Photography-2708-300x200.jpg","width":300,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/houstonmusicreview.com\/wordpress\/wp-content\/uploads\/2019\/11\/Kevin-Black-Photography-2708-300x200.jpg"},"medium_large":{"file":"Kevin-Black-Photography-2708-768x512.jpg","width":768,"height":512,"mime_type":"image\/jpeg","source_url":"https:\/\/houstonmusicreview.com\/wordpress\/wp-content\/uploads\/2019\/11\/Kevin-Black-Photography-2708-768x512.jpg"},"post-thumbnail":{"file":"Kevin-Black-Photography-2708-680x300.jpg","width":680,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/houstonmusicreview.com\/wordpress\/wp-content\/uploads\/2019\/11\/Kevin-Black-Photography-2708-680x300.jpg"},"full":{"file":"Kevin-Black-Photography-2708.jpg","width":1000,"height":667,"mime_type":"image\/jpeg","source_url":"https:\/\/houstonmusicreview.com\/wordpress\/wp-content\/uploads\/2019\/11\/Kevin-Black-Photography-2708.jpg"}},"image_meta":{"aperture":"2.8","credit":"","camera":"Canon EOS-1D Mark IV","caption":"","created_timestamp":"1573418883","copyright":"","focal_length":"400","iso":"2500","shutter_speed":"0.0025","title":"","orientation":"0","keywords":[]}},"post":7188,"source_url":"https:\/\/houstonmusicreview.com\/wordpress\/wp-content\/uploads\/2019\/11\/Kevin-Black-Photography-2708.jpg","filename":"Kevin-Black-Photography-2708.jpg","filesize":280583,"_links":{"self":[{"href":"https:\/\/houstonmusicreview.com\/wordpress\/wp-json\/wp\/v2\/media\/7200","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/houstonmusicreview.com\/wordpress\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/houstonmusicreview.com\/wordpress\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/houstonmusicreview.com\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/houstonmusicreview.com\/wordpress\/wp-json\/wp\/v2\/comments?post=7200"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":7188,"href":"https:\/\/houstonmusicreview.com\/wordpress\/wp-json\/wp\/v2\/posts\/7188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}