{"id":7253,"date":"2019-11-14T02:33:17","date_gmt":"2019-11-14T02:33:17","guid":{"rendered":"http:\/\/houstonmusicreview.com\/wordpress\/wp-content\/uploads\/2019\/11\/Kevin-Black-Photography-3009.jpg"},"modified":"2019-11-14T02:33:17","modified_gmt":"2019-11-14T02:33:17","slug":"kevin-black-photography-3009","status":"inherit","type":"attachment","link":"https:\/\/houstonmusicreview.com\/wordpress\/2019\/11\/14\/vetsaid-toyota-center-houston-tx-photos\/kevin-black-photography-3009\/","title":{"rendered":"Kevin Black Photography-3009"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-7253","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/houstonmusicreview.com\/wordpress\/wp-content\/uploads\/2019\/11\/Kevin-Black-Photography-3009.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"240\" src=\"https:\/\/houstonmusicreview.com\/wordpress\/wp-content\/uploads\/2019\/11\/Kevin-Black-Photography-3009-300x240.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/houstonmusicreview.com\/wordpress\/wp-content\/uploads\/2019\/11\/Kevin-Black-Photography-3009-300x240.jpg 300w, https:\/\/houstonmusicreview.com\/wordpress\/wp-content\/uploads\/2019\/11\/Kevin-Black-Photography-3009-768x614.jpg 768w, https:\/\/houstonmusicreview.com\/wordpress\/wp-content\/uploads\/2019\/11\/Kevin-Black-Photography-3009.jpg 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-attachment-id=\"7253\" data-permalink=\"https:\/\/houstonmusicreview.com\/wordpress\/2019\/11\/14\/vetsaid-toyota-center-houston-tx-photos\/kevin-black-photography-3009\/\" data-orig-file=\"https:\/\/houstonmusicreview.com\/wordpress\/wp-content\/uploads\/2019\/11\/Kevin-Black-Photography-3009.jpg\" data-orig-size=\"1000,800\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;3.2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS-1D Mark IV&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1573426582&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;400&quot;,&quot;iso&quot;:&quot;2000&quot;,&quot;shutter_speed&quot;:&quot;0.0025&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Kevin Black Photography-3009\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/houstonmusicreview.com\/wordpress\/wp-content\/uploads\/2019\/11\/Kevin-Black-Photography-3009.jpg\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1000,"height":800,"file":"2019\/11\/Kevin-Black-Photography-3009.jpg","sizes":{"thumbnail":{"file":"Kevin-Black-Photography-3009-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/houstonmusicreview.com\/wordpress\/wp-content\/uploads\/2019\/11\/Kevin-Black-Photography-3009-150x150.jpg"},"medium":{"file":"Kevin-Black-Photography-3009-300x240.jpg","width":300,"height":240,"mime_type":"image\/jpeg","source_url":"https:\/\/houstonmusicreview.com\/wordpress\/wp-content\/uploads\/2019\/11\/Kevin-Black-Photography-3009-300x240.jpg"},"medium_large":{"file":"Kevin-Black-Photography-3009-768x614.jpg","width":768,"height":614,"mime_type":"image\/jpeg","source_url":"https:\/\/houstonmusicreview.com\/wordpress\/wp-content\/uploads\/2019\/11\/Kevin-Black-Photography-3009-768x614.jpg"},"post-thumbnail":{"file":"Kevin-Black-Photography-3009-680x300.jpg","width":680,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/houstonmusicreview.com\/wordpress\/wp-content\/uploads\/2019\/11\/Kevin-Black-Photography-3009-680x300.jpg"},"full":{"file":"Kevin-Black-Photography-3009.jpg","width":1000,"height":800,"mime_type":"image\/jpeg","source_url":"https:\/\/houstonmusicreview.com\/wordpress\/wp-content\/uploads\/2019\/11\/Kevin-Black-Photography-3009.jpg"}},"image_meta":{"aperture":"3.2","credit":"","camera":"Canon EOS-1D Mark IV","caption":"","created_timestamp":"1573426582","copyright":"","focal_length":"400","iso":"2000","shutter_speed":"0.0025","title":"","orientation":"0","keywords":[]}},"post":7188,"source_url":"https:\/\/houstonmusicreview.com\/wordpress\/wp-content\/uploads\/2019\/11\/Kevin-Black-Photography-3009.jpg","filename":"Kevin-Black-Photography-3009.jpg","filesize":389884,"_links":{"self":[{"href":"https:\/\/houstonmusicreview.com\/wordpress\/wp-json\/wp\/v2\/media\/7253","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/houstonmusicreview.com\/wordpress\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/houstonmusicreview.com\/wordpress\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/houstonmusicreview.com\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/houstonmusicreview.com\/wordpress\/wp-json\/wp\/v2\/comments?post=7253"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":7188,"href":"https:\/\/houstonmusicreview.com\/wordpress\/wp-json\/wp\/v2\/posts\/7188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}